{"id":14791,"date":"2025-10-17T08:30:06","date_gmt":"2025-10-17T08:30:06","guid":{"rendered":"https:\/\/filtreau.nl\/?p=14791"},"modified":"2025-11-02T21:37:10","modified_gmt":"2025-11-02T21:37:10","slug":"filtreau-chez-select-koi-usa","status":"publish","type":"post","link":"https:\/\/filtreau.nl\/fr\/filtreau-bij-select-koi-usa\/","title":{"rendered":"Filtreau chez Select Koi aux \u00c9tats-Unis : un aper\u00e7u des coulisses"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14791\" class=\"elementor elementor-14791\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-586d986 e-flex e-con-boxed e-con e-parent\" data-id=\"586d986\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff4446 elementor-widget elementor-widget-text-editor\" data-id=\"1ff4446\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quiconque prend les carpes koi au s\u00e9rieux sait que la qualit\u00e9 de l\u2019eau est le c\u0153ur d\u2019un bassin sain et de poissons en bonne sant\u00e9. Chez Select Koi, dans le Tennessee, aux \u00c9tats-Unis, le propri\u00e9taire Hunter a \u00e9lev\u00e9 cela au rang d\u2019art. Sa passion pour les nishikigoi (koi) de haute qualit\u00e9 exige un syst\u00e8me de filtration aussi fiable et professionnel que son approche \u2014 pour ses clients \u00e9galement ! C\u2019est pourquoi il a opt\u00e9 pour une installation compl\u00e8te de <\/span><b>Filtres Filtreau Excellent<\/b><span style=\"font-weight: 400;\">, compl\u00e9t\u00e9 par <\/span><b>Filtres trickle<\/b><span style=\"font-weight: 400;\"> et <\/span><b>M\u00e9dias filtrants Mountain Tree <\/b><span style=\"font-weight: 400;\">\u00e0 installer dans une pisciculture. Il s\u2019agit sp\u00e9cifiquement du Filtreau Excellent <a href=\"https:\/\/filtreau.nl\/fr\/?s=Excellent+BIO+DRUM+100+XXL&amp;post_type=product\">BIO DRUM 100 XXL<\/a> et la <a href=\"https:\/\/filtreau.nl\/fr\/?s=Excellent+BIO+DRUM+100+XXL&amp;post_type=product\">COMBI DRUM 80\/100 XXL MOUNTAIN TREE<\/a> filtres.<br \/><\/span><\/p><p><span style=\"font-weight: 400;\">Dans cette histoire \u00e0 succ\u00e8s, nous vous emmenons chez un client pisciculteur de Hunter (Select Koi) et vous montrons pourquoi cette installation est l\u2019exemple parfait de la mani\u00e8re dont la technologie et le savoir-faire se rejoignent dans le monde des carpes koi.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed50790 e-flex e-con-boxed e-con e-parent\" data-id=\"ed50790\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af96045 elementor-widget elementor-widget-heading\" data-id=\"af96045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui est Hunter et qu\u2019est-ce que Select Koi ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a25cbd elementor-widget elementor-widget-text-editor\" data-id=\"3a25cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Select Koi est situ\u00e9e \u00e0 Sevierville, dans le Tennessee, et est connue pour l\u2019importation de carpes koi de haute qualit\u00e9 directement de Niigata, au Japon. Hunter a commenc\u00e9 modestement, mais est devenu un nom bien \u00e9tabli dans le monde du koi aux \u00c9tats-Unis. Ses bassins et r\u00e9servoirs sont con\u00e7us pour permettre aux koi de grandir dans des conditions optimales et de se distinguer par leur sant\u00e9 et leur apparence.<\/span><\/p><p><span style=\"font-weight: 400;\">Ce niveau de professionnalisation n\u00e9cessite un syst\u00e8me de filtration qui fait bien plus qu\u2019\u00e9liminer les impuret\u00e9s de l\u2019eau. Il doit garantir stabilit\u00e9, clart\u00e9 et fiabilit\u00e9, jour apr\u00e8s jour.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8a3a15 e-flex e-con-boxed e-con e-parent\" data-id=\"d8a3a15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-171c994 elementor-widget elementor-widget-heading\" data-id=\"171c994\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi le Filtreau Excellent est le bon choix\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b86f6f3 elementor-widget elementor-widget-text-editor\" data-id=\"b86f6f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Hunter a choisi le <\/span><a href=\"https:\/\/filtreau.nl\/fr\/assortiment\/filtres\/ligne-excellent\/\"><b>Gamme de filtres Filtreau Excellent<\/b><\/a><span style=\"font-weight: 400;\">, car ces syst\u00e8mes de filtration offrent une combinaison de :<\/span><\/p><ol><li><b>Filtration m\u00e9canique puissante<\/b><span style=\"font-weight: 400;\">. Cela \u00e9limine facilement les particules de salet\u00e9 grossi\u00e8res et fines.<\/span><\/li><li><b>Fonctionnement \u00e9co\u00e9nerg\u00e9tique<\/b><span style=\"font-weight: 400;\">. Extr\u00eamement important lorsqu\u2019il s\u2019agit de grands volumes d\u2019eau de bassin.<\/span><\/li><li><b>Durabilit\u00e9<\/b><span style=\"font-weight: 400;\">. Des mat\u00e9riaux robustes qui durent de nombreuses ann\u00e9es.<\/span><\/li><\/ol><p><b>Fiabilit\u00e9<\/b><span style=\"font-weight: 400;\">. Filtreau propose un syst\u00e8me qui ne vous laissera pas tomber, m\u00eame en cas d\u2019utilisation intensive.<\/span><\/p><p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 cette installation, Hunter maintient des dizaines de milliers de litres d\u2019eau de bassin parfaitement clairs, sans compromettre la sant\u00e9 de ses poissons.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-673f7f1 elementor-widget elementor-widget-heading\" data-id=\"673f7f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le r\u00f4le des Trickles et de Mountain Tree\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e02b69e elementor-widget elementor-widget-text-editor\" data-id=\"e02b69e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En plus des filtres Excellent, Select Koi utilise <\/span><b>Filtres trickle<\/b><span style=\"font-weight: 400;\"> et <\/span><b>M\u00e9dias filtrants Mountain Tree<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Filtres trickle<\/b><span style=\"font-weight: 400;\"> assurent une saturation maximale en oxyg\u00e8ne de l\u2019eau et la d\u00e9gradation biologique des substances nocives telles que l\u2019ammoniac et les nitrites. C\u2019est essentiel en cas de forte densit\u00e9 de poissons. <\/span><span style=\"font-weight: 400;\"><br \/><br \/><\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>M\u00e9dias filtrants Mountain Tree<\/b><span style=\"font-weight: 400;\"> offrent une surface \u00e9norme pour les bact\u00e9ries b\u00e9n\u00e9fiques. Ces bact\u00e9ries constituent le moteur biologique de tout syst\u00e8me de filtration et maintiennent la stabilit\u00e9 des param\u00e8tres de l\u2019eau.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">La combinaison de ces technologies cr\u00e9e un \u00e9cosyst\u00e8me qui se rapproche fortement de l\u2019habitat naturel des carpes koi.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23788ed1 e-flex e-con-boxed e-con e-parent\" data-id=\"23788ed1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67b088f1 e-con-full e-flex e-con e-child\" data-id=\"67b088f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e58bc91 elementor-widget elementor-widget-heading\" data-id=\"7e58bc91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Filtreau Trickles<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-666738ce elementor-hidden-mobile elementor-widget elementor-widget-ld_button\" data-id=\"666738ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/filtreau.nl\/fr\/uv-c\/\"class=\"elementor-button btn btn-solid btn-icon-right btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Bekijk alle trickles\" class=\"btn-txt\">\n\t\t\t\t\t\tVoir tous les trickles\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46199643 elementor-widget elementor-widget-ld_woo_products_list\" data-id=\"46199643\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ld_woo_products_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce\"><ul class=\"products columns-4 reset-ul lqd-prods-row\" id=\"lqd-prods-row-46199643\">\n<li class=\"lqd-prod-item excellent-lijn filters trickle col-md-3 col-sm-6 col-xs-12 product type-product post-3861 status-publish first instock product_cat-excellent-lijn product_cat-filters product_cat-trickle product_tag-combi-drum product_tag-low has-post-thumbnail product-type-simple\">\n\t<div class=\"ld-sp ld-sp-mhs-1\">\n\t\t<figure class=\"ld-sp-img pos-rel\">\n\t\t<a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-25-30-low\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"RUISSELER POUR COMBI DRUM 25\/30 FAIBLE\" srcset=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant-300x300.png 300w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant-150x150.png 150w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant-600x600.png 600w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant-12x12.png 12w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC20CDT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-Transparant.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" itemprop=\"image\" \/><\/a>\t\t<\/figure>\n\t\t<div class=\"ld-sp-info d-flex flex-wrap align-items-center font-weight-medium\">\n\t\t\t<div class=\"ld-sp-info-inner\">\n\t\t\t<h3><a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-25-30-low\/\">RUISSELER POUR COMBI DRUM 25\/30 FAIBLE<\/a><\/h3><p class=\"ld-sp-price pos-rel\">\n<\/p>\t\t\t<\/div>\n\t\t\t<div class=\"ld-sp-btns d-flex align-items-center justify-content-start\">\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:3861,&quot;item_id&quot;:&quot;WMC20CDT&quot;,&quot;item_name&quot;:&quot;TRICKLE VOOR COMBI DRUM 25\\\/30 LOW&quot;,&quot;sku&quot;:&quot;WMC20CDT&quot;,&quot;price&quot;:0,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Filters&quot;,&quot;item_category2&quot;:&quot;Excellent lijn&quot;,&quot;id&quot;:&quot;WMC20CDT&quot;,&quot;item_brand&quot;:&quot;&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/filtreau.nl\\\/fr\\\/product\\\/trickle-voor-combi-drum-25-30-low\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;simple&quot;}\"><\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li>\n<li class=\"lqd-prod-item excellent-lijn filters trickle col-md-3 col-sm-6 col-xs-12 product type-product post-3865 status-publish instock product_cat-excellent-lijn product_cat-filters product_cat-trickle product_tag-combi-drum product_tag-low has-post-thumbnail product-type-simple\">\n\t<div class=\"ld-sp ld-sp-mhs-1\">\n\t\t<figure class=\"ld-sp-img pos-rel\">\n\t\t<a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-20-25-low\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 300&#039;%2F%3E\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail ld-lazyload\" alt=\"RUISSELER POUR COMBI DRUM 20\/25 FAIBLE\" itemprop=\"image\" data-src=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant-300x300.png\" data-srcset=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant-300x300.png 300w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant-150x150.png 150w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant-600x600.png 600w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant-12x12.png 12w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC11PPT-COMBI-DRUM-20-25-LOW-TRICKLE-2-X-FILTER-Transparant.png 1000w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" data-aspect=\"1\" \/><\/a>\t\t<\/figure>\n\t\t<div class=\"ld-sp-info d-flex flex-wrap align-items-center font-weight-medium\">\n\t\t\t<div class=\"ld-sp-info-inner\">\n\t\t\t<h3><a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-20-25-low\/\">RUISSELER POUR COMBI DRUM 20\/25 FAIBLE<\/a><\/h3><p class=\"ld-sp-price pos-rel\">\n<\/p>\t\t\t<\/div>\n\t\t\t<div class=\"ld-sp-btns d-flex align-items-center justify-content-start\">\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:3865,&quot;item_id&quot;:&quot;WMC11PPT&quot;,&quot;item_name&quot;:&quot;TRICKLE VOOR COMBI DRUM 20\\\/25 LOW&quot;,&quot;sku&quot;:&quot;WMC11PPT&quot;,&quot;price&quot;:0,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Filters&quot;,&quot;item_category2&quot;:&quot;Excellent lijn&quot;,&quot;id&quot;:&quot;WMC11PPT&quot;,&quot;item_brand&quot;:&quot;&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/filtreau.nl\\\/fr\\\/product\\\/trickle-voor-combi-drum-20-25-low\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:2,&quot;product_type&quot;:&quot;simple&quot;}\"><\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li>\n<li class=\"lqd-prod-item excellent-lijn filters trickle col-md-3 col-sm-6 col-xs-12 product type-product post-3869 status-publish instock product_cat-excellent-lijn product_cat-filters product_cat-trickle product_tag-combi-drum has-post-thumbnail product-type-simple\">\n\t<div class=\"ld-sp ld-sp-mhs-1\">\n\t\t<figure class=\"ld-sp-img pos-rel\">\n\t\t<a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-25-30\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 300&#039;%2F%3E\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail ld-lazyload\" alt=\"RUISSELER POUR COMBI DRUM 25\/30\" itemprop=\"image\" data-src=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2-300x300.png\" data-srcset=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2-300x300.png 300w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2-150x150.png 150w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2-600x600.png 600w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2-12x12.png 12w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC10PPT-COMBI-DRUM-25-30-TRICKLE-2-X-FILTER-2.png 1000w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" data-aspect=\"1\" \/><\/a>\t\t<\/figure>\n\t\t<div class=\"ld-sp-info d-flex flex-wrap align-items-center font-weight-medium\">\n\t\t\t<div class=\"ld-sp-info-inner\">\n\t\t\t<h3><a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-25-30\/\">RUISSELER POUR COMBI DRUM 25\/30<\/a><\/h3><p class=\"ld-sp-price pos-rel\">\n<\/p>\t\t\t<\/div>\n\t\t\t<div class=\"ld-sp-btns d-flex align-items-center justify-content-start\">\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:3869,&quot;item_id&quot;:&quot;WMC10PPT&quot;,&quot;item_name&quot;:&quot;TRICKLE VOOR COMBI DRUM 25\\\/30&quot;,&quot;sku&quot;:&quot;WMC10PPT&quot;,&quot;price&quot;:0,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Filters&quot;,&quot;item_category2&quot;:&quot;Excellent lijn&quot;,&quot;id&quot;:&quot;WMC10PPT&quot;,&quot;item_brand&quot;:&quot;&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/filtreau.nl\\\/fr\\\/product\\\/trickle-voor-combi-drum-25-30\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:3,&quot;product_type&quot;:&quot;simple&quot;}\"><\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li>\n<li class=\"lqd-prod-item excellent-lijn filters trickle col-md-3 col-sm-6 col-xs-12 product type-product post-3833 status-publish last instock product_cat-excellent-lijn product_cat-filters product_cat-trickle product_tag-combi-drum has-post-thumbnail product-type-simple\">\n\t<div class=\"ld-sp ld-sp-mhs-1\">\n\t\t<figure class=\"ld-sp-img pos-rel\">\n\t\t<a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-30-45l\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 300&#039;%2F%3E\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail ld-lazyload\" alt=\"RUISSELER POUR COMBI DRUM 30\/45L\" itemprop=\"image\" data-src=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant-300x300.png\" data-srcset=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant-300x300.png 300w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant-150x150.png 150w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant-600x600.png 600w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant-12x12.png 12w, https:\/\/filtreau.nl\/wp-content\/uploads\/2024\/01\/WMC32ILT-COMBI-DRUM-30-45-L-TRICKLE-2-X-FILTER-Transparant.png 1000w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" data-aspect=\"1\" \/><\/a>\t\t<\/figure>\n\t\t<div class=\"ld-sp-info d-flex flex-wrap align-items-center font-weight-medium\">\n\t\t\t<div class=\"ld-sp-info-inner\">\n\t\t\t<h3><a href=\"https:\/\/filtreau.nl\/fr\/product\/trickle-voor-combi-drum-30-45l\/\">RUISSELER POUR COMBI DRUM 30\/45L<\/a><\/h3><p class=\"ld-sp-price pos-rel\">\n<\/p>\t\t\t<\/div>\n\t\t\t<div class=\"ld-sp-btns d-flex align-items-center justify-content-start\">\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:3833,&quot;item_id&quot;:&quot;WMC32ILT&quot;,&quot;item_name&quot;:&quot;TRICKLE VOOR COMBI DRUM 30\\\/45L&quot;,&quot;sku&quot;:&quot;WMC32ILT&quot;,&quot;price&quot;:0,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Filters&quot;,&quot;item_category2&quot;:&quot;Excellent lijn&quot;,&quot;id&quot;:&quot;WMC32ILT&quot;,&quot;item_brand&quot;:&quot;&quot;,&quot;productlink&quot;:&quot;https:\\\/\\\/filtreau.nl\\\/fr\\\/product\\\/trickle-voor-combi-drum-30-45l\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:4,&quot;product_type&quot;:&quot;simple&quot;}\"><\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d05359 e-flex e-con-boxed e-con e-parent\" data-id=\"8d05359\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02c1830 elementor-widget elementor-widget-heading\" data-id=\"02c1830\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu\u2019est-ce que cela signifie pour les koi de Hunter ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52585fa elementor-widget elementor-widget-text-editor\" data-id=\"52585fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pour Hunter, cela signifie qu\u2019il peut s\u00e9lectionner, \u00e9lever et vendre des koi en toute confiance, en sachant que la qualit\u00e9 de l\u2019eau est toujours au plus haut niveau.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fead72c e-flex e-con-boxed e-con e-parent\" data-id=\"fead72c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fd10190 e-con-full e-flex e-con e-child\" data-id=\"fd10190\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c84a63 elementor-widget elementor-widget-spacer\" data-id=\"1c84a63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcdd3ab e-con-full e-flex e-con e-child\" data-id=\"bcdd3ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01abf34 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"01abf34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a5710b1bbb63\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > L\u2019eau reste en permanence cristalline<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64673b9 e-flex e-con-boxed e-con e-parent\" data-id=\"64673b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c2f26e e-con-full e-flex e-con e-child\" data-id=\"1c2f26e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf52b76 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"cf52b76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a5710b1bc07b\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Les koi pr\u00e9sentent des couleurs \u00e9clatantes et une croissance saine<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f33fec e-con-full e-flex e-con e-child\" data-id=\"6f33fec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9ff5c elementor-widget elementor-widget-spacer\" data-id=\"4a9ff5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b5c994 e-flex e-con-boxed e-con e-parent\" data-id=\"4b5c994\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b27f94d e-con-full e-flex e-con e-child\" data-id=\"b27f94d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39bee38 elementor-widget elementor-widget-spacer\" data-id=\"39bee38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37edf17 e-con-full e-flex e-con e-child\" data-id=\"37edf17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1250dd elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"e1250dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a5710b1bc54b\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Le stress et les maladies sont r\u00e9duits au minimum gr\u00e2ce \u00e0 la stabilit\u00e9 des param\u00e8tres de l\u2019eau.\n<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2142460 e-flex e-con-boxed e-con e-parent\" data-id=\"2142460\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4eb8868 elementor-widget elementor-widget-heading\" data-id=\"4eb8868\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Que pouvons-nous en apprendre ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10dac26 elementor-widget elementor-widget-text-editor\" data-id=\"10dac26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Het verhaal van Select Koi onderstreept een belangrijke les: investeren in hoogwaardige filtratie betaalt zich altijd terug. Of je nu een professionele dealer bent of een hobbyist met een particuliere vijver. Systemen zoals <\/span><b>Filtreau Excellent<\/b><span style=\"font-weight: 400;\">, <\/span><b>Trickels<\/b><span style=\"font-weight: 400;\"> et <\/span><b>Mountain Tree<\/b><span style=\"font-weight: 400;\"> font la diff\u00e9rence entre un bassin qui \u201ctourne\u201d et un bassin qui excelle r\u00e9ellement.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45fcce4 e-flex e-con-boxed e-con e-parent\" data-id=\"45fcce4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a05c2f0 elementor-widget elementor-widget-heading\" data-id=\"a05c2f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conclusion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffda91 elementor-widget elementor-widget-text-editor\" data-id=\"8ffda91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le choix de Hunter pour les filtres Filtreau Excellent montre que la qualit\u00e9 est reconnue et appr\u00e9ci\u00e9e dans le monde entier. Avec la bonne combinaison de filtration m\u00e9canique, biologique et innovante, m\u00eame les conditions les plus exigeantes peuvent \u00eatre ma\u00eetris\u00e9es.<\/span><\/p><p><span style=\"font-weight: 400;\">Vous souhaitez en savoir plus sur les possibilit\u00e9s offertes par Filtreau Excellent et sur la fa\u00e7on dont ces filtres peuvent faire passer votre bassin au niveau sup\u00e9rieur ? Visitez nos pages produits et d\u00e9couvrez la puissance de Filtreau.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dcdff0 e-flex e-con-boxed e-con e-parent\" data-id=\"5dcdff0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff8c1a3 elementor-widget elementor-widget-video\" data-id=\"ff8c1a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/cK1q4oSTnIk&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e7b6fd e-flex e-con-boxed e-con e-parent\" data-id=\"1e7b6fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4b5d8d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e4b5d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8201316 e-flex e-con-boxed e-con e-parent\" data-id=\"8201316\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-662c2c6 elementor-widget elementor-widget-heading\" data-id=\"662c2c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quemment pos\u00e9es sur Filtreau Excellent, Trickles et Mountain Tree<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b505978 elementor-widget__width-initial elementor-widget elementor-widget-ld_accordion\" data-id=\"b505978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-lg accordion-side-spacing accordion-title-bg-transparent accordion-active-has-fill\" id=\"accordion-6a5710b1be464\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1891\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1891\" data-target=\"#collapse-1891\" data-bs-target=\"#collapse-1891\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-1891\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Qui est Hunter de Select Koi et pourquoi a-t-il choisi les filtres Filtreau Excellent ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1891\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1891\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Hunter est le propri\u00e9taire de Select Koi dans le Tennessee (\u00c9tats-Unis), un importateur sp\u00e9cialis\u00e9 de nishikigoi japonais. Il a choisi Filtreau Excellent parce que ces filtres allient puissance, fiabilit\u00e9 et durabilit\u00e9 \u2014 des \u00e9l\u00e9ments essentiels pour un \u00e9levage professionnel de carpes koi.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1892\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1892\" data-target=\"#collapse-1892\" data-bs-target=\"#collapse-1892\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1892\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Qu\u2019est-ce qui rend la gamme de filtres Filtreau Excellent unique ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1892\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1892\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les filtres Filtreau Excellent se distinguent par une filtration m\u00e9canique puissante, un fonctionnement \u00e9co\u00e9nerg\u00e9tique, des mat\u00e9riaux robustes et une fiabilit\u00e9 constante. Ils ont \u00e9t\u00e9 con\u00e7us pour garder les grands bassins parfaitement clairs, m\u00eame en cas de forte charge.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1893\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1893\" data-target=\"#collapse-1893\" data-bs-target=\"#collapse-1893\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1893\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Quel r\u00f4le jouent les filtres Trickle dans l\u2019installation de Hunter ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1893\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1893\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les filtres Trickle assurent une saturation maximale en oxyg\u00e8ne et la d\u00e9gradation biologique des substances nocives telles que l\u2019ammoniac et les nitrites. C\u2019est crucial lorsqu\u2019il y a une forte densit\u00e9 de poissons, comme chez les \u00e9leveurs professionnels de carpes koi.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1894\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1894\" data-target=\"#collapse-1894\" data-bs-target=\"#collapse-1894\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1894\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Qu\u2019est-ce que le m\u00e9dia filtrant Mountain Tree et pourquoi est-il utilis\u00e9 ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1894\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1894\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le m\u00e9dia filtrant Mountain Tree offre une grande surface pour les bact\u00e9ries b\u00e9n\u00e9fiques. Ces bact\u00e9ries assurent un \u00e9quilibre biologique stable et maintiennent des param\u00e8tres d\u2019eau s\u00fbrs et sains pour les carpes koi.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1895\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1895\" data-target=\"#collapse-1895\" data-bs-target=\"#collapse-1895\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1895\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Quels avantages Hunter observe-t-il chez ses koi gr\u00e2ce \u00e0 ce syst\u00e8me de filtration ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1895\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1895\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les koi de Hunter nagent dans une eau cristalline, pr\u00e9sentent des couleurs vives, grandissent en bonne sant\u00e9 et subissent moins de stress. Cela est d\u00fb \u00e0 la qualit\u00e9 d\u2019eau stable que Filtreau Excellent assure en combinaison avec les Trickles et Mountain Tree.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1896\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1896\" data-target=\"#collapse-1896\" data-bs-target=\"#collapse-1896\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1896\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Les filtres Filtreau Excellent sont-ils r\u00e9serv\u00e9s aux professionnels ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1896\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1896\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><b><span style=\"font-weight: 400;\">Non, en plus des \u00e9leveurs professionnels de koi, ces filtres sont \u00e9galement id\u00e9aux pour les passionn\u00e9s qui souhaitent faire passer leur bassin au niveau sup\u00e9rieur. Investir dans une filtration de haute qualit\u00e9 garantit toujours une meilleure qualit\u00e9 d\u2019eau et des poissons en meilleure sant\u00e9.<\/span><\/b><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1897\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a5710b1be464\" data-bs-parent=\"#accordion-6a5710b1be464\" href=\"#collapse-1897\" data-target=\"#collapse-1897\" data-bs-target=\"#collapse-1897\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1897\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Qu\u2019est-ce qui rend la combinaison de Filtreau Excellent, Trickles et Mountain Tree si performante ?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1897\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-6a5710b1be464\" role=\"tabpanel\" aria-labelledby=\"heading-1897\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cette combinaison exploite la puissance de la filtration m\u00e9canique, biologique et innovante. Ensemble, elles cr\u00e9ent un \u00e9cosyst\u00e8me proche de l\u2019habitat naturel des koi et offrent une stabilit\u00e9 durable.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Wie serieus bezig is met koi weet dat waterkwaliteit het hart vormt van een gezonde vijver en gezonde vissen. Bij Select Koi in Tennessee, Verenigde Staten, heeft eigenaar Hunter dit tot kunst verheven. Zijn passie voor topkwaliteit nishikigoi (koi) vraagt om een filtersysteem dat net zo betrouwbaar en professioneel is als zijn aanpak. Ook voor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"wds_primary_category":0,"footnotes":""},"categories":[214,662],"tags":[],"class_list":["post-14791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filters","category-mountain-tree","lqd-prod-item",null,"col-md-3 col-sm-6 col-xs-12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filtreau Excellent bij Select Koi USA<\/title>\n<meta name=\"description\" content=\"Ontdek hoe Hunter van Select Koi in de VS zijn koi vijvers uitrust met Filtreau Excellent filters met trickles en Mountain Tree!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filtreau.nl\/fr\/filtreau-chez-select-koi-usa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtreau Excellent bij Select Koi USA\" \/>\n<meta property=\"og:description\" content=\"Ontdek hoe Hunter van Select Koi in de VS zijn koi vijvers uitrust met Filtreau Excellent filters met trickles en Mountain Tree!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filtreau.nl\/fr\/filtreau-chez-select-koi-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Filtreau\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T08:30:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-02T21:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_wimaca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_wimaca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/\"},\"author\":{\"name\":\"admin_wimaca\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/#\\\/schema\\\/person\\\/155ec78f932d870e7b510a5254075d12\"},\"headline\":\"Filtreau bij Select Koi in de VS: een kijkje achter de schermen\",\"datePublished\":\"2025-10-17T08:30:06+00:00\",\"dateModified\":\"2025-11-02T21:37:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/\"},\"wordCount\":792,\"image\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filtreau.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg\",\"articleSection\":[\"Filters\",\"Mountain Tree\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/\",\"url\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/\",\"name\":\"Filtreau Excellent bij Select Koi USA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filtreau.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg\",\"datePublished\":\"2025-10-17T08:30:06+00:00\",\"dateModified\":\"2025-11-02T21:37:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/#\\\/schema\\\/person\\\/155ec78f932d870e7b510a5254075d12\"},\"description\":\"Ontdek hoe Hunter van Select Koi in de VS zijn koi vijvers uitrust met Filtreau Excellent filters met trickles en Mountain Tree!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filtreau.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/filtreau.nl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/filtreau-bij-select-koi-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/filtreau.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filtreau bij Select Koi in de VS: een kijkje achter de schermen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/\",\"name\":\"Filtreau\",\"description\":\"Schoon en helder water voor vijvers en zwembaden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filtreau.nl\\\/en\\\/#\\\/schema\\\/person\\\/155ec78f932d870e7b510a5254075d12\",\"name\":\"admin_wimaca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g\",\"caption\":\"admin_wimaca\"},\"sameAs\":[\"http:\\\/\\\/filtreau.nl\"],\"url\":\"https:\\\/\\\/filtreau.nl\\\/fr\\\/author\\\/admin_wimaca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filtreau Excellent chez Select Koi USA","description":"D\u00e9couvrez comment Hunter de Select Koi aux \u00c9tats-Unis \u00e9quipe ses bassins \u00e0 carpes koi avec des filtres Filtreau Excellent, trickles et Mountain Tree !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filtreau.nl\/fr\/filtreau-chez-select-koi-usa\/","og_locale":"fr_FR","og_type":"article","og_title":"Filtreau Excellent bij Select Koi USA","og_description":"Ontdek hoe Hunter van Select Koi in de VS zijn koi vijvers uitrust met Filtreau Excellent filters met trickles en Mountain Tree!","og_url":"https:\/\/filtreau.nl\/fr\/filtreau-chez-select-koi-usa\/","og_site_name":"Filtreau","article_published_time":"2025-10-17T08:30:06+00:00","article_modified_time":"2025-11-02T21:37:10+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","type":"image\/jpeg"}],"author":"admin_wimaca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_wimaca","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#article","isPartOf":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/"},"author":{"name":"admin_wimaca","@id":"https:\/\/filtreau.nl\/en\/#\/schema\/person\/155ec78f932d870e7b510a5254075d12"},"headline":"Filtreau bij Select Koi in de VS: een kijkje achter de schermen","datePublished":"2025-10-17T08:30:06+00:00","dateModified":"2025-11-02T21:37:10+00:00","mainEntityOfPage":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/"},"wordCount":792,"image":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","articleSection":["Filters","Mountain Tree"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/","url":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/","name":"Filtreau Excellent chez Select Koi USA","isPartOf":{"@id":"https:\/\/filtreau.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#primaryimage"},"image":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","datePublished":"2025-10-17T08:30:06+00:00","dateModified":"2025-11-02T21:37:10+00:00","author":{"@id":"https:\/\/filtreau.nl\/en\/#\/schema\/person\/155ec78f932d870e7b510a5254075d12"},"description":"D\u00e9couvrez comment Hunter de Select Koi aux \u00c9tats-Unis \u00e9quipe ses bassins \u00e0 carpes koi avec des filtres Filtreau Excellent, trickles et Mountain Tree !","breadcrumb":{"@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#primaryimage","url":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","contentUrl":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/filtreau.nl\/filtreau-bij-select-koi-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/filtreau.nl\/"},{"@type":"ListItem","position":2,"name":"Filtreau bij Select Koi in de VS: een kijkje achter de schermen"}]},{"@type":"WebSite","@id":"https:\/\/filtreau.nl\/en\/#website","url":"https:\/\/filtreau.nl\/en\/","name":"Filtreau","description":"Schoon en helder water voor vijvers en zwembaden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filtreau.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/filtreau.nl\/en\/#\/schema\/person\/155ec78f932d870e7b510a5254075d12","name":"admin_wimaca","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12a9b82ecb3dbcfff970420af383620f0b02febef091af1ce02eb3879c5e1c84?s=96&d=mm&r=g","caption":"admin_wimaca"},"sameAs":["http:\/\/filtreau.nl"],"url":"https:\/\/filtreau.nl\/fr\/author\/admin_wimaca\/"}]}},"jetpack_featured_media_url":"https:\/\/filtreau.nl\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-10-at-11.20.21-3.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/posts\/14791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/comments?post=14791"}],"version-history":[{"count":44,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/posts\/14791\/revisions"}],"predecessor-version":[{"id":14893,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/posts\/14791\/revisions\/14893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/media\/14852"}],"wp:attachment":[{"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/media?parent=14791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/categories?post=14791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filtreau.nl\/fr\/wp-json\/wp\/v2\/tags?post=14791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}